{"id":8991,"date":"2026-09-01T20:03:58","date_gmt":"2026-09-01T11:03:58","guid":{"rendered":"https:\/\/truach.co.jp\/wordpress\/?post_type=works&#038;p=8991"},"modified":"2026-09-01T20:04:37","modified_gmt":"2026-09-01T11:04:37","slug":"%e5%a5%88%e8%89%af%e7%9c%8c-%e5%a5%88%e8%89%af%e5%b8%82-2","status":"publish","type":"works","link":"https:\/\/truach.co.jp\/wordpress\/works\/%e5%a5%88%e8%89%af%e7%9c%8c-%e5%a5%88%e8%89%af%e5%b8%82-2\/","title":{"rendered":"\u5948\u826f\u770c \u5948\u826f\u5e02 K\u69d8\u90b8"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">2026\/9\/1<\/p>\n","protected":false},"featured_media":8992,"menu_order":0,"template":"","format":"standard","meta":{"_acf_changed":false},"works_cat":[7,6,13,4,14],"class_list":["post-8991","works","type-works","status-publish","format-standard","has-post-thumbnail","hentry","works_cat-smart-house","works_cat-reform","works_cat-solarpanel","works_cat-solarpanel-storagebattery","works_cat-storagebattery"],"acf":[],"_links":{"self":[{"href":"https:\/\/truach.co.jp\/wordpress\/wp-json\/wp\/v2\/works\/8991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/truach.co.jp\/wordpress\/wp-json\/wp\/v2\/works"}],"about":[{"href":"https:\/\/truach.co.jp\/wordpress\/wp-json\/wp\/v2\/types\/works"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/truach.co.jp\/wordpress\/wp-json\/wp\/v2\/media\/8992"}],"wp:attachment":[{"href":"https:\/\/truach.co.jp\/wordpress\/wp-json\/wp\/v2\/media?parent=8991"}],"wp:term":[{"taxonomy":"works_cat","embeddable":true,"href":"https:\/\/truach.co.jp\/wordpress\/wp-json\/wp\/v2\/works_cat?post=8991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}